{"id":6756,"date":"2018-10-24T12:25:53","date_gmt":"2018-10-24T10:25:53","guid":{"rendered":"https:\/\/www.bustreff.de\/busmagazin\/?p=6756"},"modified":"2026-06-26T15:03:49","modified_gmt":"2026-06-26T13:03:49","slug":"duh-klage-gegen-limburg-und-oldenburg","status":"publish","type":"post","link":"https:\/\/www.bustreff.de\/busmagazin\/duh-klage-gegen-limburg-und-oldenburg\/","title":{"rendered":"DUH: Klage gegen Limburg und Oldenburg"},"content":{"rendered":"<div id=\"pl-6756\"  class=\"panel-layout\" >\n<div id=\"pg-6756-0\"  class=\"panel-grid panel-no-style\"  data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;,&quot;cell_alignment&quot;:&quot;flex-start&quot;}\" >\n<div id=\"pgc-6756-0-0\"  class=\"panel-grid-cell\"  data-weight=\"0.5\" >\n<div id=\"panel-6756-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>Die Deutsche Umwelthilfe (DUH) hat zwei weitere Klagen zur Durchsetzung der \u201eSauberen Luft\u201c durch Diesel-Fahrverbote sowie weiterer konkreter Ma\u00dfnahmen f\u00fcr Limburg (Hessen) und Oldenburg (Niedersachsen) eingereicht. In beiden St\u00e4dten wird der EU-Grenzwert f\u00fcr Stickstoffdioxid (NO<sub>2<\/sub>) von 40 Mikrogramm pro Kubikmeter (\u00b5g \/m\u00b3) im Jahresmittel erheblich \u00fcberschritten. Weitere Klagen f\u00fcr Bielefeld, Hagen, Oberhausen, Wuppertal und Freiburg sollen im November 2018 folgen. Damit klagt die DUH dann in 34 durch Dieselabgase belasteten St\u00e4dten.<br \/>\nZiel der Klagen ist die Einhaltung des seit 2010 verbindlich geltenden NO<sub>2<\/sub>-Luftqualit\u00e4tsgrenzwerts noch im Jahr 2019, so die DUH. Das Bundesverwaltungsgericht in Leipzig hatte in seinem Grundsatzurteil vom 27. Februar 2018 dies als letztm\u00f6glichen Zeitpunkt h\u00f6chstrichterlich festgelegt.<\/p>\n<p>In Limburg wurde laut Umweltbundesamt an der Messstation Schiede I im Jahr 2017 immer noch ein Wert von 58 \u00b5g NO<sub>2<\/sub>\/m\u00b3 ermittelt. In Oldenburg liegt der Wert f\u00fcr NO<sub>2<\/sub> an der Messstelle Heiligengeistwall bei 49 \u00b5g\/m\u00b3. Hier besteht nach Auffassung der DUH ein besonders dringender Handlungsbedarf.<\/p>\n<p>&nbsp;<\/p>\n<p>Bildquelle: pixabay\/pixel2013<\/p>\n<p>(Symbolbild)<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pgc-6756-0-1\"  class=\"panel-grid-cell\"  data-weight=\"0.5\" >\n<div id=\"panel-6756-0-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"1\" data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t><\/p>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/www.bustreff.de\/busmagazin\/wp-content\/uploads\/2018\/10\/pixel2013-512x365.jpg\" width=\"512\" height=\"365\" srcset=\"https:\/\/www.bustreff.de\/busmagazin\/wp-content\/uploads\/2018\/10\/pixel2013-512x365.jpg 512w, https:\/\/www.bustreff.de\/busmagazin\/wp-content\/uploads\/2018\/10\/pixel2013-200x143.jpg 200w, https:\/\/www.bustreff.de\/busmagazin\/wp-content\/uploads\/2018\/10\/pixel2013-768x547.jpg 768w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" alt=\"\" decoding=\"async\" loading=\"lazy\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Deutsche Umwelthilfe (DUH) hat zwei weitere Klagen zur Durchsetzung der \u201eSauberen Luft\u201c durch Diesel-Fahrverbote sowie weiterer konkreter Ma\u00dfnahmen f\u00fcr Limburg (Hessen) und Oldenburg (Niedersachsen) eingereicht. In beiden St\u00e4dten wird der EU-Grenzwert f\u00fcr Stickstoffdioxid (NO2) von 40 Mikrogramm pro Kubikmeter (\u00b5g \/m\u00b3) im Jahresmittel erheblich \u00fcberschritten. Weitere Klagen f\u00fcr Bielefeld, Hagen, Oberhausen, Wuppertal und Freiburg &#8230; <a href=\"https:\/\/www.bustreff.de\/busmagazin\/duh-klage-gegen-limburg-und-oldenburg\/\" class=\"more-link\">mehr<\/a><\/p>\n","protected":false},"author":6,"featured_media":6759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-busmagazin"],"_links":{"self":[{"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/posts\/6756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/comments?post=6756"}],"version-history":[{"count":7,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/posts\/6756\/revisions"}],"predecessor-version":[{"id":21453,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/posts\/6756\/revisions\/21453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/media\/6759"}],"wp:attachment":[{"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/media?parent=6756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/categories?post=6756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bustreff.de\/busmagazin\/wp-json\/wp\/v2\/tags?post=6756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}